{"id":4641,"date":"2025-10-24T14:19:22","date_gmt":"2025-10-24T12:19:22","guid":{"rendered":"https:\/\/www.skischule-neuastenberg.de\/aries-homepage\/"},"modified":"2025-11-08T23:04:24","modified_gmt":"2025-11-08T22:04:24","slug":"aries-homepage","status":"publish","type":"page","link":"https:\/\/www.skischule-neuastenberg.de\/nl\/","title":{"rendered":"Startpagina"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4641","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Skischool Neuastenberg - Winterberg Postwiese<\/title>\n<meta name=\"description\" content=\"Skischool Winterberg - Neuastenberg. Skilessen voor kinderen en volwassenen met onze skileraren. Ski\u00ebn in Winterberg. Online boeken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.skischule-neuastenberg.de\/nl\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skischool Neuastenberg - Winterberg Postwiese\" \/>\n<meta property=\"og:description\" content=\"Skischool Winterberg - Neuastenberg. Skilessen voor kinderen en volwassenen met onze skileraren. Ski\u00ebn in Winterberg. Online boeken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.skischule-neuastenberg.de\/nl\/\" \/>\n<meta property=\"og:site_name\" content=\"Skischule Neuastenberg - Winterberg - Postwiese\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SkischuleNeuastenberg\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-08T22:04:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/\",\"url\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/\",\"name\":\"Skischool Neuastenberg - Winterberg Postwiese\",\"isPartOf\":{\"@id\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/#website\"},\"datePublished\":\"2025-10-24T12:19:22+00:00\",\"dateModified\":\"2025-11-08T22:04:24+00:00\",\"description\":\"Skischool Winterberg - Neuastenberg. Skilessen voor kinderen en volwassenen met onze skileraren. Ski\u00ebn in Winterberg. Online boeken.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.skischule-neuastenberg.de\/nl\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Startpagina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/#website\",\"url\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/\",\"name\":\"Skischule Neuastenberg - Winterberg - Postwiese\",\"description\":\"SKIFAHREN LERNEN IN WINTERBERG SAUERLAND\",\"publisher\":{\"@id\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/#organization\",\"name\":\"Skischule Neuastenberg\",\"url\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.skischule-neuastenberg.de\/wp-content\/uploads\/2022\/07\/Skischule-Winterberg-Neuastenberg-Logo.webp\",\"contentUrl\":\"https:\/\/www.skischule-neuastenberg.de\/wp-content\/uploads\/2022\/07\/Skischule-Winterberg-Neuastenberg-Logo.webp\",\"width\":125,\"height\":86,\"caption\":\"Skischule Neuastenberg\"},\"image\":{\"@id\":\"https:\/\/www.skischule-neuastenberg.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SkischuleNeuastenberg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Skischool Neuastenberg - Winterberg Postwiese","description":"Skischool Winterberg - Neuastenberg. Skilessen voor kinderen en volwassenen met onze skileraren. Ski\u00ebn in Winterberg. Online boeken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.skischule-neuastenberg.de\/nl\/","og_locale":"nl_NL","og_type":"article","og_title":"Skischool Neuastenberg - Winterberg Postwiese","og_description":"Skischool Winterberg - Neuastenberg. Skilessen voor kinderen en volwassenen met onze skileraren. Ski\u00ebn in Winterberg. Online boeken.","og_url":"https:\/\/www.skischule-neuastenberg.de\/nl\/","og_site_name":"Skischule Neuastenberg - Winterberg - Postwiese","article_publisher":"https:\/\/www.facebook.com\/SkischuleNeuastenberg","article_modified_time":"2025-11-08T22:04:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"8 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.skischule-neuastenberg.de\/nl\/","url":"https:\/\/www.skischule-neuastenberg.de\/nl\/","name":"Skischool Neuastenberg - Winterberg Postwiese","isPartOf":{"@id":"https:\/\/www.skischule-neuastenberg.de\/nl\/#website"},"datePublished":"2025-10-24T12:19:22+00:00","dateModified":"2025-11-08T22:04:24+00:00","description":"Skischool Winterberg - Neuastenberg. Skilessen voor kinderen en volwassenen met onze skileraren. Ski\u00ebn in Winterberg. Online boeken.","breadcrumb":{"@id":"https:\/\/www.skischule-neuastenberg.de\/nl\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.skischule-neuastenberg.de\/nl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.skischule-neuastenberg.de\/nl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.skischule-neuastenberg.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Startpagina"}]},{"@type":"WebSite","@id":"https:\/\/www.skischule-neuastenberg.de\/nl\/#website","url":"https:\/\/www.skischule-neuastenberg.de\/nl\/","name":"Skischule Neuastenberg - Winterberg - Postwiese","description":"SKIFAHREN LERNEN IN WINTERBERG SAUERLAND","publisher":{"@id":"https:\/\/www.skischule-neuastenberg.de\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.skischule-neuastenberg.de\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.skischule-neuastenberg.de\/nl\/#organization","name":"Skischule Neuastenberg","url":"https:\/\/www.skischule-neuastenberg.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.skischule-neuastenberg.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.skischule-neuastenberg.de\/wp-content\/uploads\/2022\/07\/Skischule-Winterberg-Neuastenberg-Logo.webp","contentUrl":"https:\/\/www.skischule-neuastenberg.de\/wp-content\/uploads\/2022\/07\/Skischule-Winterberg-Neuastenberg-Logo.webp","width":125,"height":86,"caption":"Skischule Neuastenberg"},"image":{"@id":"https:\/\/www.skischule-neuastenberg.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SkischuleNeuastenberg"]}]}},"_links":{"self":[{"href":"https:\/\/www.skischule-neuastenberg.de\/nl\/wp-json\/wp\/v2\/pages\/4641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skischule-neuastenberg.de\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.skischule-neuastenberg.de\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.skischule-neuastenberg.de\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skischule-neuastenberg.de\/nl\/wp-json\/wp\/v2\/comments?post=4641"}],"version-history":[{"count":6,"href":"https:\/\/www.skischule-neuastenberg.de\/nl\/wp-json\/wp\/v2\/pages\/4641\/revisions"}],"predecessor-version":[{"id":4748,"href":"https:\/\/www.skischule-neuastenberg.de\/nl\/wp-json\/wp\/v2\/pages\/4641\/revisions\/4748"}],"wp:attachment":[{"href":"https:\/\/www.skischule-neuastenberg.de\/nl\/wp-json\/wp\/v2\/media?parent=4641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}